{"id":176390,"date":"2023-01-08T01:00:00","date_gmt":"2023-01-08T06:00:00","guid":{"rendered":"https:\/\/ifamnews.com\/?p=176390"},"modified":"2022-12-25T14:08:26","modified_gmt":"2022-12-25T19:08:26","slug":"transexuales-y-transg-neros-en-la-adolescencia-una-nueva-moda","status":"publish","type":"post","link":"https:\/\/ifamnews.com\/es\/transexuales-y-transg-neros-en-la-adolescencia-una-nueva-moda","title":{"rendered":"Transexuales y transg\u00e9neros en la adolescencia: \u00bfuna nueva moda?"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p><em>Sonia ten\u00eda 16 a\u00f1os cuando todo el mundo le ayud\u00f3 en su transici\u00f3n. Nadie le cuestion\u00f3 y sus amigos y familiares pensaban que era feliz.<\/em> <\/p>\n\n\n\n<p><em>Varios a\u00f1os m\u00e1s tarde, en el presente con 23 a\u00f1os, no tiene pecho, ni ovarios, ni \u00fatero, ni conserva su nombre en el registro.<\/em><\/p>\n\n\n\n<p><em>Lo \u00fanico que no ha cambiado son sus problemas de salud mental que van en aumento.<\/em><\/p>\n\n\n\n<p><em>Ahora ella no se reconoce como chico, pero nadie le ayuda.<\/em><\/p>\n\n\n\n<p><em>Tanto ella como su familia se sienten desesperados y solos frente a esta situaci\u00f3n.<\/em><\/p>\n\n\n\n<p>Esta es una historia real, tan s\u00f3lo con nombre ficticio, de las cientos y cientos que est\u00e1n saliendo a la luz cada vez m\u00e1s a menudo y que podemos encontrar en la p\u00e1gina de la agrupaci\u00f3n de padres AMANDA<a href=\"#_ftn1\" id=\"_ftnref1\">[1]<\/a>. Muchas familias se enfrentan a la llamada Disforia Acelerada o Disforia de G\u00e9nero de Inicio R\u00e1pido (DGIR) de sus hijos menores de edad, que se autoidentifican como \u201ctrans\u201d o \u201cno binarios\u201d. Lo peculiar es que surge de forma repentina.<\/p>\n\n\n\n<p>Los padres de estos chicos quieren lo mejor para sus hijos, pero se encuentran con dudas y temores que nadie les resuelve. A los adolescentes que no se identifican con su sexo biol\u00f3gico se les presenta como \u00fanica soluci\u00f3n la deriva al equipo de orientaci\u00f3n LGTBIQ del instituto de lo que no informan a los padres o a la Unidad de G\u00e9nero o de Transexualidad e Identidad de G\u00e9nero en donde comienzan el proceso de transici\u00f3n. All\u00ed les dicen que tienen derecho a hormonarse. En ning\u00fan momento se preocupan por sus antecedentes o situaci\u00f3n mental.<\/p>\n\n\n\n<p>Los profesionales m\u00e9dicos y psic\u00f3logos est\u00e1n atados de manos o no quieren mostrarse contrarios a esta dictadura del g\u00e9nero. A los menores se les permite hormonarse y someterse a una intervenci\u00f3n quir\u00fargica sin necesidad de presentar un informe donde se expongan las posibles causas del malestar del menor.<\/p>\n\n\n\n<p>Muchos adolescentes que sufren inconformidad con su sexo biol\u00f3gico presentan una serie de enfermedades mentales: trastornos de conducta alimenticia como la anorexia, autoestima baja, trastorno l\u00edmite de la personalidad, depresi\u00f3n, autismo, han presentado tentativas de suicidio o autolesiones. Tambi\u00e9n hay casos que han sufrido abusos sexuales o que no aceptan su cuerpo y han sufrido bullying. Los hay incluso que tienen altas capacidades con dificultades de socializaci\u00f3n.<\/p>\n\n\n\n<p>Las consecuencias que para un menor puede tener someterse a este proceso de cambio de sexo son terribles y por vida. Luego ya no hay vuelta atr\u00e1s.<\/p>\n\n\n\n<p>El aumento tan dr\u00e1stico de adolescentes que piden el cambio de sexo es claramente una muestra de que se trata de un contagio social, resultado de la informaci\u00f3n que les llega por las redes sociales, del grupo de amigos e incluso de los centros educativos. Por ejemplo, en Madrid, la Unidad de Identidad de G\u00e9nero ha visto un incremento de solicitudes de atenci\u00f3n del 500% entre 2017 y 2019, la mayor\u00eda de ellas de chicas muy j\u00f3venes. Pero como toda moda que es global, ya en otros pa\u00edses nos llevan la delantera. En Gran Breta\u00f1a este incremento ha sido del 4000% entre 2009 y 2018.<\/p>\n\n\n\n<p>Debemos estar m\u00e1s atentos que nunca para salvar a nuestros hijos de las garras de este monstruo ideol\u00f3gico.<\/p>\n\n\n\n<p>Est\u00e1 claro que la transexualidad en los menores es una moda, pero cuyas heridas f\u00edsicas y morales quedan marcadas en los chicos para siempre.<\/p>\n\n\n\n<p>Puedes encontrar m\u00e1s informaci\u00f3n sobre el da\u00f1o de la ideolog\u00eda de g\u00e9nero en mi libro <strong><em>\u201c99 respuestas frente a la ideolog\u00eda de g\u00e9nero. Una gu\u00eda con perspectiva cristiana desde la adolescencia\u201d<\/em><\/strong>. Contacta en: beatrizmf@asociaci\u00f3nlibertas.es<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><a href=\"#_ftnref1\" id=\"_ftn1\">[1]<\/a> <a href=\"https:\/\/mailchi.mp\/5acd9b943493\/lo-que-cuentan-las-familias\">https:\/\/mailchi.mp\/5acd9b943493\/lo-que-cuentan-las-familias<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El aumento tan dr\u00e1stico de adolescentes que piden el cambio de sexo es claramente una muestra de que se trata de un contagio social, resultado de la informaci\u00f3n que les llega por las redes sociales, del grupo de amigos e incluso de los centros educativos<\/p>\n","protected":false},"author":567,"featured_media":176392,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"mc4wp_mailchimp_campaign":[],"jnews-multi-image_gallery":[],"jnews_single_post":{"subtitle":"Las consecuencias que para un menor puede tener someterse a este proceso de cambio de sexo son terribles y por vida. Luego ya no hay vuelta atr\u00e1s","format":"standard","video":"","gallery":"","source_name":"","source_url":"","via_name":"","via_url":"","override_template":"0","override":[{"template":"2","single_blog_custom":"","parallax":"1","fullscreen":"1","layout":"right-sidebar-narrow","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"float","share_float_style":"share-normal","show_share_counter":"1","show_view_counter":"1","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","show_post_reading_time":"1","post_reading_time_wpm":"300","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","show_prev_next_post":"0","show_popup_post":"0","number_popup_post":"1","show_author_box":"1","show_post_related":"0","show_inline_post_related":"0"}],"override_image_size":"0","image_override":[{"single_post_thumbnail_size":"crop-715","single_post_gallery_size":"crop-715"}],"trending_post":"0","trending_post_position":"meta","trending_post_label":"Trending","sponsored_post":"0","sponsored_post_label":"Sponsored by","sponsored_post_name":"","sponsored_post_url":"","sponsored_post_logo_enable":"0","sponsored_post_logo":"","sponsored_post_desc":"","disable_ad":"0"},"jnews_primary_category":{"id":"765"},"jnews_social_meta":{"fb_title":"","fb_description":"","fb_image":"","twitter_title":"","twitter_description":"","twitter_image":""},"jnews_override_counter":{"override_view_counter":"0","view_counter_number":"0","override_share_counter":"0","share_counter_number":"0","override_like_counter":"0","like_counter_number":"0","override_dislike_counter":"0","dislike_counter_number":"0"},"footnotes":""},"categories":[765,810,815],"tags":[20273,22283,1804],"class_list":["post-176390","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-es","category-foreground-es","category-breaking-news-es","tag-adolescencia","tag-lgtbiq","tag-transgenero"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.9 (Yoast SEO v27.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Transexuales y transg\u00e9neros en la adolescencia: \u00bfuna nueva moda? - IFN<\/title>\n<meta name=\"description\" content=\"Las consecuencias que tiene para un menor someterse a este proceso de cambio de sexo son terribles y por vida. Luego ya no hay vuelta atr\u00e1s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ifamnews.com\/es\/transexuales-y-transg-neros-en-la-adolescencia-una-nueva-moda\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transexuales y transg\u00e9neros en la adolescencia: \u00bfuna nueva moda?\" \/>\n<meta property=\"og:description\" content=\"Las consecuencias que tiene para un menor someterse a este proceso de cambio de sexo son terribles y por vida. Luego ya no hay vuelta atr\u00e1s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ifamnews.com\/es\/transexuales-y-transg-neros-en-la-adolescencia-una-nueva-moda\" \/>\n<meta property=\"og:site_name\" content=\"IFN\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/iFamNews\" \/>\n<meta property=\"article:author\" content=\"https:\/\/facebook.com\/buscandorespuestas2017\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-08T06:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ifamnews.com\/wp-content\/uploads\/2022\/12\/Adolescentes-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1707\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Beatriz Montes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/ABeatrizMontesF\" \/>\n<meta name=\"twitter:site\" content=\"@iFamNewsEN\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Beatriz Montes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Transexuales y transg\u00e9neros en la adolescencia: \u00bfuna nueva moda? - IFN","description":"Las consecuencias que tiene para un menor someterse a este proceso de cambio de sexo son terribles y por vida. Luego ya no hay vuelta atr\u00e1s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ifamnews.com\/es\/transexuales-y-transg-neros-en-la-adolescencia-una-nueva-moda","og_locale":"es_ES","og_type":"article","og_title":"Transexuales y transg\u00e9neros en la adolescencia: \u00bfuna nueva moda?","og_description":"Las consecuencias que tiene para un menor someterse a este proceso de cambio de sexo son terribles y por vida. Luego ya no hay vuelta atr\u00e1s.","og_url":"https:\/\/ifamnews.com\/es\/transexuales-y-transg-neros-en-la-adolescencia-una-nueva-moda","og_site_name":"IFN","article_publisher":"https:\/\/www.facebook.com\/iFamNews","article_author":"https:\/\/facebook.com\/buscandorespuestas2017","article_published_time":"2023-01-08T06:00:00+00:00","og_image":[{"width":1707,"height":2560,"url":"https:\/\/ifamnews.com\/wp-content\/uploads\/2022\/12\/Adolescentes-scaled.jpg","type":"image\/jpeg"}],"author":"Beatriz Montes","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/ABeatrizMontesF","twitter_site":"@iFamNewsEN","twitter_misc":{"Escrito por":"Beatriz Montes","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/ifamnews.com\/es\/transexuales-y-transg-neros-en-la-adolescencia-una-nueva-moda#article","isPartOf":{"@id":"https:\/\/ifamnews.com\/es\/transexuales-y-transg-neros-en-la-adolescencia-una-nueva-moda"},"author":{"name":"Beatriz Montes","@id":"https:\/\/ifamnews.com\/en\/#\/schema\/person\/aed4de9ddd8d78c90a083d39f23f98b9"},"headline":"Transexuales y transg\u00e9neros en la adolescencia: \u00bfuna nueva moda?","datePublished":"2023-01-08T06:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/ifamnews.com\/es\/transexuales-y-transg-neros-en-la-adolescencia-una-nueva-moda"},"wordCount":649,"commentCount":0,"publisher":{"@id":"https:\/\/ifamnews.com\/en\/#organization"},"image":{"@id":"https:\/\/ifamnews.com\/es\/transexuales-y-transg-neros-en-la-adolescencia-una-nueva-moda#primaryimage"},"thumbnailUrl":"https:\/\/ifamnews.com\/wp-content\/uploads\/2022\/12\/Adolescentes-scaled.jpg","keywords":["adolescencia","LGTBIQ","transg\u00e9nero"],"articleSection":["Cultura","Foreground","\u00daLTIMAS NOTICIAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ifamnews.com\/es\/transexuales-y-transg-neros-en-la-adolescencia-una-nueva-moda#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ifamnews.com\/es\/transexuales-y-transg-neros-en-la-adolescencia-una-nueva-moda","url":"https:\/\/ifamnews.com\/es\/transexuales-y-transg-neros-en-la-adolescencia-una-nueva-moda","name":"Transexuales y transg\u00e9neros en la adolescencia: \u00bfuna nueva moda? - IFN","isPartOf":{"@id":"https:\/\/ifamnews.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ifamnews.com\/es\/transexuales-y-transg-neros-en-la-adolescencia-una-nueva-moda#primaryimage"},"image":{"@id":"https:\/\/ifamnews.com\/es\/transexuales-y-transg-neros-en-la-adolescencia-una-nueva-moda#primaryimage"},"thumbnailUrl":"https:\/\/ifamnews.com\/wp-content\/uploads\/2022\/12\/Adolescentes-scaled.jpg","datePublished":"2023-01-08T06:00:00+00:00","description":"Las consecuencias que tiene para un menor someterse a este proceso de cambio de sexo son terribles y por vida. Luego ya no hay vuelta atr\u00e1s.","breadcrumb":{"@id":"https:\/\/ifamnews.com\/es\/transexuales-y-transg-neros-en-la-adolescencia-una-nueva-moda#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ifamnews.com\/es\/transexuales-y-transg-neros-en-la-adolescencia-una-nueva-moda"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ifamnews.com\/es\/transexuales-y-transg-neros-en-la-adolescencia-una-nueva-moda#primaryimage","url":"https:\/\/ifamnews.com\/wp-content\/uploads\/2022\/12\/Adolescentes-scaled.jpg","contentUrl":"https:\/\/ifamnews.com\/wp-content\/uploads\/2022\/12\/Adolescentes-scaled.jpg","width":1707,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/ifamnews.com\/es\/transexuales-y-transg-neros-en-la-adolescencia-una-nueva-moda#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ifamnews.com\/de"},{"@type":"ListItem","position":2,"name":"\u041a\u0443\u043b\u0442\u0443\u0440\u0430","item":"https:\/\/ifamnews.com\/sr\/kategorija\/kultura-sr"},{"@type":"ListItem","position":3,"name":"Transexuales y transg\u00e9neros en la adolescencia: \u00bfuna nueva moda?"}]},{"@type":"WebSite","@id":"https:\/\/ifamnews.com\/en\/#website","url":"https:\/\/ifamnews.com\/en\/","name":"IFN","description":"International Family News Network","publisher":{"@id":"https:\/\/ifamnews.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ifamnews.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/ifamnews.com\/en\/#organization","name":"iFamNews","url":"https:\/\/ifamnews.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ifamnews.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/ifamnews.com\/wp-content\/uploads\/2020\/01\/Share-logo.png","contentUrl":"https:\/\/ifamnews.com\/wp-content\/uploads\/2020\/01\/Share-logo.png","width":200,"height":200,"caption":"iFamNews"},"image":{"@id":"https:\/\/ifamnews.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/iFamNews","https:\/\/x.com\/iFamNewsEN"]},{"@type":"Person","@id":"https:\/\/ifamnews.com\/en\/#\/schema\/person\/aed4de9ddd8d78c90a083d39f23f98b9","name":"Beatriz Montes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5ef4f8cf0f3807ae571fc4b7c1e62cd02b7bdd9a1796ca51a0641acf56453b19?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5ef4f8cf0f3807ae571fc4b7c1e62cd02b7bdd9a1796ca51a0641acf56453b19?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5ef4f8cf0f3807ae571fc4b7c1e62cd02b7bdd9a1796ca51a0641acf56453b19?s=96&d=mm&r=g","caption":"Beatriz Montes"},"description":"Married with six children. Teacher of Catholic topic. Beatriz Montes is Master of Science for the family and she is graduated in Family studies. Author of the books \"Against the Gender Ideology: educating in Freedom from childhood\" and \"99 responses to the Gender Ideology\". Publisher and writer of articles on her blog https:\/\/buscandorespuestasemet.com\/. Beatriz is a member of several relevant institution as \"Enraizados\", \"Libertas\" and \"The Traditional Post\".","sameAs":["https:\/\/facebook.com\/buscandorespuestas2017","https:\/\/x.com\/https:\/\/twitter.com\/ABeatrizMontesF"],"url":"https:\/\/ifamnews.com\/es\/author\/beatriz-montes"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ifamnews.com\/es\/wp-json\/wp\/v2\/posts\/176390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ifamnews.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ifamnews.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ifamnews.com\/es\/wp-json\/wp\/v2\/users\/567"}],"replies":[{"embeddable":true,"href":"https:\/\/ifamnews.com\/es\/wp-json\/wp\/v2\/comments?post=176390"}],"version-history":[{"count":1,"href":"https:\/\/ifamnews.com\/es\/wp-json\/wp\/v2\/posts\/176390\/revisions"}],"predecessor-version":[{"id":176391,"href":"https:\/\/ifamnews.com\/es\/wp-json\/wp\/v2\/posts\/176390\/revisions\/176391"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ifamnews.com\/es\/wp-json\/wp\/v2\/media\/176392"}],"wp:attachment":[{"href":"https:\/\/ifamnews.com\/es\/wp-json\/wp\/v2\/media?parent=176390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ifamnews.com\/es\/wp-json\/wp\/v2\/categories?post=176390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ifamnews.com\/es\/wp-json\/wp\/v2\/tags?post=176390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}