{"id":33357,"date":"2020-10-23T01:00:38","date_gmt":"2020-10-23T06:00:38","guid":{"rendered":"https:\/\/ifamnews.com\/cenerentola-lesbica-e-un-drago-transgender-viktor-orb-n-insorge\/"},"modified":"2020-10-21T10:47:48","modified_gmt":"2020-10-21T15:47:48","slug":"lesbisches-aschenputtel-undtranssexuellen-drachen","status":"publish","type":"post","link":"https:\/\/ifamnews.com\/de\/lesbisches-aschenputtel-undtranssexuellen-drachen","title":{"rendered":"Viktor Orb\u00e1n wehrt sich gegen lesbisches Aschenputtel und transsexuellen Drachen"},"content":{"rendered":"\n<p>Nicht \u00fcberall herrschen die gleichen Sitten. Unter den Mitgliedstaaten der Europ\u00e4ischen Union sind die Herangehensweisen in Bezug auf Grundwerte derart verschieden, dass sich die vielgepriesene F\u00f6rderung gemeinsamer Werte als Schim\u00e4re entpuppt. Zur Erl\u00e4uterung ein Beispiel: W\u00e4hrend in Italien die Regierungsmehrheit beabsichtigt, <a href=\"https:\/\/ifamnews.com\/it\/il-ddl-zan-che-impone-lideologia-gender-nelle-scuole\">per Gesetz eine Art LGBT+-Feiertag an Schulen zu verabschieden<\/a>, errichtet im nicht weit entfernten Ungarn der Premierminister Viktor Orb\u00e1n eine immaterielle Barriere angesichts des Versuchs, Kindern mithilfe eines exzentrischen M\u00e4rchenbuchs die Gender-Ideologie einzutrichtern.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><strong>Ver\u00f6ffentlichung des Buches<\/strong><\/strong><\/h3>\n\n\n\n<p>Unl\u00e4ngst ist die \u00f6ffentliche Meinung des Landes auf dieses Thema aufmerksam geworden. Am 21. September ver\u00f6ffentlichte der Verlag <em>Labrisz Leszbikus Egyes\u00fclet<\/em> das Buch <em>Meseorsz\u00e1g Mindenki\u00e9<\/em>, zu Deutsch: Die Welt der M\u00e4rchen f\u00fcr alle. Es handelt sich um eine Zusammenstellung traditioneller M\u00e4rchen, die in \u201einkludierender\u201c Sprache, oder besser gesagt \u201epolitisch korrekter\u201c Lesart \u00fcberarbeitet wurden. M\u00e4rchenprinzen und keusche Hofdamen, lebet wohl! An ihrer Stelle findet man nun als neue Hauptfiguren ein lesbisches Aschenputtel und einen transsexuellen Drachen &#8211; neben weiteren Vertretern anderer Minderheitengruppen. <a href=\"https:\/\/time.com\/5897312\/hungary-book-lgbt-rights\/\">Der Verleger sagte<\/a>, es sei das erste Kinderbuch zum Thema LGBT+ in ungarischer Sprache: \u201eWir wollten jenen eine Stimme geben, die keine haben\u201c.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><strong>Die Kontroverse<\/strong><\/strong><\/h3>\n\n\n\n<p>Die Idee, diese \u201eStimme\u201c k\u00f6nne Kindern Gender-Botschaften einfl\u00fcstern, fand jedoch keinen Anklang. Bereits 90.000 Ungarn haben sich der <a href=\"https:\/\/citizengo.org\/hu\/fm\/182339-vegye-le-kinalatabol-az-lmbtq-mesekonyvet-pagony-gyerekkonyvesbolt-tobbi-arusitohely?fbclid=IwAR0OFqi0hZpBQGaAbwSqVP7oJnlU3GA1FkEtKoxfD554NpcZJtLeg1lT8OI&amp;utm_source=mandiner&amp;utm_medium=link&amp;utm_campaign=mandiner_202009&amp;utm_source=mandiner&amp;utm_medium=link&amp;utm_campaign=mandiner_202009\">Petition von CitizenGo<\/a> angeschlossen, welche Buchl\u00e4den dazu auffordert, die M\u00e4rchensammlung aus dem Verkauf zu nehmen. Auch die Aktion von D\u00far\u00f3 D\u00f3ra, Abgeordnete und Vizevorsitzende der nationalistischen Partei <em><a href=\"https:\/\/mihazank.hu\/\">Mi Hazank Mozgalom<\/a> <\/em>(\u201eUnsere Heimat-Bewegung \u201c) sorgte f\u00fcr heftige Diskussionen, als sie vor laufender Kamera <a href=\"https:\/\/hirtv.hu\/ahirtvhirei\/ujabb-mesekonyvet-semmisitett-meg-duro-dora-2509687\">Seiten aus dem Buch herausriss<\/a>. \u201eNein zu homosexueller Propaganda, der unsere Kinder ausgesetzt werden\u201c, donnerte sie. Auf der gleichen Wellenl\u00e4nge liegt L\u00e9n\u00e1rd Borb\u00e9ly, B\u00fcrgermeister des Budapester Stadtbezirks Csepel. Auf Facebook postete er, er habe das Buch in allen Kinderg\u00e4rten und Kitas seines Bezirks verboten. \u00dcberzeugend schloss er die Botschaft mit den Worten: \u201eLasst unsere Kinder in Ruhe!\u201c<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Reaktion der Regierung<\/strong><\/h3>\n\n\n\n<p>Ein Mitglied der Kommunalverwaltung und Angeh\u00f6riger der Regierungspartei <em>Fidesz<\/em> zeigte sich emp\u00f6rt \u00fcber die blo\u00dfe Vorstellung, ein solches Buch k\u00f6nne wom\u00f6glich in einer Schule landen. Seine Sorge scheint nicht abwegig. Die liberale Partei <em>Momentum<\/em> (die bei den Europawahlen 2019 auf dem dritten Platz landete) will anscheinend <a href=\"https:\/\/origo.hu\/itthon\/20200820-genderszemleletu-ovodai-oktatast-vezetne-be-a-momentum.html\">Pflichtkurse zur Geschlechtserziehung in Kinderg\u00e4rten einf\u00fchren, die unter dem Banner des Regenbogens stehen<\/a>. Die Angelegenheit ist bis in die oberste Parteiebene vorgedrungen. Gergely Guly\u00e1s, Amtsminister des Ministerpr\u00e4sidenten, gab dazu <a href=\"https:\/\/telex.hu\/belfold\/2020\/10\/08\/meseorszag-mindenkie-ovoda-gulyas-gergely-kiskoruak-veszelyeztetese\">folgende Stellungnahme<\/a> ab: \u201eWie man seine Sexualit\u00e4t auslebt, ist Privatsache und jedem selbst \u00fcberlassen, doch gibt es ein Limit: homosexuelle Propaganda gegen\u00fcber Kindern ist nicht erlaubt\u201c. Diese Aussage steht in Einklang mit den <a href=\"https:\/\/mediaklikk.hu\/miniszterelnoki-interjuk\/cikk\/2020\/10\/04\/orban-viktor-miniszterelnoki-interju-vasarnapi-ujsag-oktober-4\/\">Worten von Premierminister Orb\u00e1n<\/a>: \u201eUngarns Gesetze zur Homosexualit\u00e4t beruhen auf einem \u00e4u\u00dferst toleranten und geduldigen Ansatz. Aber es gibt eine Grenze, die nicht \u00fcberschritten werden darf: Lasst unsere Kinder in Ruhe.\u201c<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Anti-Gender-Politik und Drohungen<\/strong><\/h3>\n\n\n\n<p>Ungarns Widerstand gegen das Vorhaben, eine Gender-Ideologie einzuf\u00fchren, verwundert nicht. Im Mai beschloss das ungarische Parlament, <a href=\"https:\/\/ifamnews.com\/de\/warum-ungarn-die-istanbul-konvention-abgelehnt-hat\">die Istanbul-Konvention zur Bek\u00e4mpfung von Gewalt gegen Frauen nicht zu ratifizieren<\/a>. Das besagte Dokument, das den Begriff Geschlecht eher in sozialem als biologischem Sinne interpretiert, widerspricht der ungarischen Verfassung, insofern diese die Ehe als Vereinigung von Mann und Frau festschreibt. Im vergangenen Fr\u00fchjahr wurde zudem <a href=\"https:\/\/ifamnews.com\/it\/gender-scontro-tra-ungheria-e-consiglio-deuropa\">eine Gesetzes\u00e4nderung verabschiedet<\/a>, in der Gender als \u201ebiologisches, auf Geburt und Genom basierendes Geschlecht\u201c definiert wird. In einem Aspekt jedoch gleichen sich alle \u00fcberall auf der Welt: n\u00e4mlich in der Gewaltbereitschaft gewisser Gruppen. So haben sowohl die Verfasserin der Petition von CitizenGo als auch die Abgeordnete, die Seiten aus dem Gender-M\u00e4rchenbuch herausgerissen hat, <a href=\"https:\/\/v4na.com\/en\/child-protection-activist-petitioning-against-lgbtq-children-s-book-receives-brutal-threats\">anonyme Drohungen erhalten<\/a>. \u201eDie Intoleranz der Toleranten\u201c ist \u00fcberall dieselbe. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e4rchenbuch mit LGBT+-Figuren sorgt in Ungarn f\u00fcr Kontroverse <\/p>\n","protected":false},"author":15,"featured_media":32130,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"mc4wp_mailchimp_campaign":[],"jnews-multi-image_gallery":[],"jnews_single_post":{"subtitle":"M\u00e4rchenbuch mit LGBT+-Figuren sorgt in Ungarn f\u00fcr Kontroverse ","format":"standard","video":"","gallery":"","source_name":"","source_url":"","via_name":"","via_url":"","override":[{"single_blog_custom":"","sidebar":"","second_sidebar":"","share_position":"","share_float_style":"","post_date_format":"","post_date_format_custom":"","post_reading_time_wpm":"","zoom_button_out_step":"1","zoom_button_in_step":"1","number_popup_post":"1"}],"image_override":[{"single_post_thumbnail_size":"","single_post_gallery_size":""}],"trending_post_position":"","trending_post_label":"","sponsored_post_label":"","sponsored_post_name":"","sponsored_post_url":"","sponsored_post_logo":"","sponsored_post_desc":""},"jnews_primary_category":{"id":"768"},"jnews_social_meta":{"fb_title":"","fb_description":"","fb_image":"","twitter_title":"","twitter_description":"","twitter_image":""},"jnews_override_counter":{"view_counter_number":"0","share_counter_number":"0","like_counter_number":"0","dislike_counter_number":"0"},"footnotes":""},"categories":[816,768],"tags":[2279,1832,6201],"class_list":["post-33357","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news-de","category-politik","tag-gender-ideologie","tag-ungarn","tag-ungheria-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.9 (Yoast SEO v27.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Viktor Orb\u00e1n wehrt sich gegen lesbisches Aschenputtel und transsexuellen Drachen - IFN<\/title>\n<meta name=\"description\" content=\"Una raccolta di fiabe con protagonisti LGBT+ aggredisce i bambini in Ungheria. Roventi polemiche. Insorge Viktor Orb\u00e1n\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ifamnews.com\/de\/lesbisches-aschenputtel-undtranssexuellen-drachen\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Viktor Orb\u00e1n wehrt sich gegen lesbisches Aschenputtel und transsexuellen Drachen\" \/>\n<meta property=\"og:description\" content=\"Una raccolta di fiabe con protagonisti LGBT+ aggredisce i bambini in Ungheria. Roventi polemiche. Insorge Viktor Orb\u00e1n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ifamnews.com\/de\/lesbisches-aschenputtel-undtranssexuellen-drachen\" \/>\n<meta property=\"og:site_name\" content=\"IFN\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/iFamNews\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-23T06:00:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ifamnews.com\/wp-content\/uploads\/2020\/10\/Image-from-Needpix.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Federico Cenci\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/fedecenci\" \/>\n<meta name=\"twitter:site\" content=\"@iFamNewsEN\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Federico Cenci\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Viktor Orb\u00e1n wehrt sich gegen lesbisches Aschenputtel und transsexuellen Drachen - IFN","description":"Una raccolta di fiabe con protagonisti LGBT+ aggredisce i bambini in Ungheria. Roventi polemiche. Insorge Viktor Orb\u00e1n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ifamnews.com\/de\/lesbisches-aschenputtel-undtranssexuellen-drachen","og_locale":"de_DE","og_type":"article","og_title":"Viktor Orb\u00e1n wehrt sich gegen lesbisches Aschenputtel und transsexuellen Drachen","og_description":"Una raccolta di fiabe con protagonisti LGBT+ aggredisce i bambini in Ungheria. Roventi polemiche. Insorge Viktor Orb\u00e1n","og_url":"https:\/\/ifamnews.com\/de\/lesbisches-aschenputtel-undtranssexuellen-drachen","og_site_name":"IFN","article_publisher":"https:\/\/www.facebook.com\/iFamNews","article_published_time":"2020-10-23T06:00:38+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/ifamnews.com\/wp-content\/uploads\/2020\/10\/Image-from-Needpix.jpg","type":"image\/jpeg"}],"author":"Federico Cenci","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/fedecenci","twitter_site":"@iFamNewsEN","twitter_misc":{"Verfasst von":"Federico Cenci","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/ifamnews.com\/de\/lesbisches-aschenputtel-undtranssexuellen-drachen#article","isPartOf":{"@id":"https:\/\/ifamnews.com\/de\/lesbisches-aschenputtel-undtranssexuellen-drachen"},"author":{"name":"Federico Cenci","@id":"https:\/\/ifamnews.com\/en\/#\/schema\/person\/555378c4ec9e01d40ab9f2b5cee0c318"},"headline":"Viktor Orb\u00e1n wehrt sich gegen lesbisches Aschenputtel und transsexuellen Drachen","datePublished":"2020-10-23T06:00:38+00:00","mainEntityOfPage":{"@id":"https:\/\/ifamnews.com\/de\/lesbisches-aschenputtel-undtranssexuellen-drachen"},"wordCount":626,"commentCount":0,"publisher":{"@id":"https:\/\/ifamnews.com\/en\/#organization"},"image":{"@id":"https:\/\/ifamnews.com\/de\/lesbisches-aschenputtel-undtranssexuellen-drachen#primaryimage"},"thumbnailUrl":"https:\/\/ifamnews.com\/wp-content\/uploads\/2020\/10\/Image-from-Needpix.jpg","keywords":["Gender Ideologie","Ungarn","Ungheria"],"articleSection":["Breaking News","Politik"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ifamnews.com\/de\/lesbisches-aschenputtel-undtranssexuellen-drachen#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ifamnews.com\/de\/lesbisches-aschenputtel-undtranssexuellen-drachen","url":"https:\/\/ifamnews.com\/de\/lesbisches-aschenputtel-undtranssexuellen-drachen","name":"Viktor Orb\u00e1n wehrt sich gegen lesbisches Aschenputtel und transsexuellen Drachen - IFN","isPartOf":{"@id":"https:\/\/ifamnews.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ifamnews.com\/de\/lesbisches-aschenputtel-undtranssexuellen-drachen#primaryimage"},"image":{"@id":"https:\/\/ifamnews.com\/de\/lesbisches-aschenputtel-undtranssexuellen-drachen#primaryimage"},"thumbnailUrl":"https:\/\/ifamnews.com\/wp-content\/uploads\/2020\/10\/Image-from-Needpix.jpg","datePublished":"2020-10-23T06:00:38+00:00","description":"Una raccolta di fiabe con protagonisti LGBT+ aggredisce i bambini in Ungheria. Roventi polemiche. Insorge Viktor Orb\u00e1n","breadcrumb":{"@id":"https:\/\/ifamnews.com\/de\/lesbisches-aschenputtel-undtranssexuellen-drachen#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ifamnews.com\/de\/lesbisches-aschenputtel-undtranssexuellen-drachen"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ifamnews.com\/de\/lesbisches-aschenputtel-undtranssexuellen-drachen#primaryimage","url":"https:\/\/ifamnews.com\/wp-content\/uploads\/2020\/10\/Image-from-Needpix.jpg","contentUrl":"https:\/\/ifamnews.com\/wp-content\/uploads\/2020\/10\/Image-from-Needpix.jpg","width":1280,"height":853},{"@type":"BreadcrumbList","@id":"https:\/\/ifamnews.com\/de\/lesbisches-aschenputtel-undtranssexuellen-drachen#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ifamnews.com\/de"},{"@type":"ListItem","position":2,"name":"Politics","item":"https:\/\/ifamnews.com\/en\/category\/politics"},{"@type":"ListItem","position":3,"name":"Viktor Orb\u00e1n wehrt sich gegen lesbisches Aschenputtel und transsexuellen Drachen"}]},{"@type":"WebSite","@id":"https:\/\/ifamnews.com\/en\/#website","url":"https:\/\/ifamnews.com\/en\/","name":"IFN","description":"International Family News Network","publisher":{"@id":"https:\/\/ifamnews.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ifamnews.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/ifamnews.com\/en\/#organization","name":"iFamNews","url":"https:\/\/ifamnews.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ifamnews.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/ifamnews.com\/wp-content\/uploads\/2020\/01\/Share-logo.png","contentUrl":"https:\/\/ifamnews.com\/wp-content\/uploads\/2020\/01\/Share-logo.png","width":200,"height":200,"caption":"iFamNews"},"image":{"@id":"https:\/\/ifamnews.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/iFamNews","https:\/\/x.com\/iFamNewsEN"]},{"@type":"Person","@id":"https:\/\/ifamnews.com\/en\/#\/schema\/person\/555378c4ec9e01d40ab9f2b5cee0c318","name":"Federico Cenci","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/535f77b8447d05f39d4ca941654f7a7b7d712f3d72f0b4b185747785f5a8e745?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/535f77b8447d05f39d4ca941654f7a7b7d712f3d72f0b4b185747785f5a8e745?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/535f77b8447d05f39d4ca941654f7a7b7d712f3d72f0b4b185747785f5a8e745?s=96&d=mm&r=g","caption":"Federico Cenci"},"description":"Federico Cenci worked from 2013 to 2017 at the Catholic Zenit press agency dealing with social and religious issues, bioethics, family policies, as well as domestic and international politics. He then continued his business with In Terris, and currently with various newspapers and periodicals. In 2020 he wrote the novel \"East Berlin 2.0 - Notes between dystopia and reality\"","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/fedecenci"],"url":"https:\/\/ifamnews.com\/de\/author\/fcenci"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ifamnews.com\/de\/wp-json\/wp\/v2\/posts\/33357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ifamnews.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ifamnews.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ifamnews.com\/de\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/ifamnews.com\/de\/wp-json\/wp\/v2\/comments?post=33357"}],"version-history":[{"count":3,"href":"https:\/\/ifamnews.com\/de\/wp-json\/wp\/v2\/posts\/33357\/revisions"}],"predecessor-version":[{"id":33393,"href":"https:\/\/ifamnews.com\/de\/wp-json\/wp\/v2\/posts\/33357\/revisions\/33393"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ifamnews.com\/de\/wp-json\/wp\/v2\/media\/32130"}],"wp:attachment":[{"href":"https:\/\/ifamnews.com\/de\/wp-json\/wp\/v2\/media?parent=33357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ifamnews.com\/de\/wp-json\/wp\/v2\/categories?post=33357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ifamnews.com\/de\/wp-json\/wp\/v2\/tags?post=33357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}