{"id":197821,"date":"2023-06-13T02:00:00","date_gmt":"2023-06-13T06:00:00","guid":{"rendered":"https:\/\/ifamnews.com\/?p=197821"},"modified":"2023-06-09T03:37:44","modified_gmt":"2023-06-09T07:37:44","slug":"christlicher-demonstrant-verhaftet-weil-er-auf-einer-lgbt-veranstaltung-aus-der-bibel-zitierte","status":"publish","type":"post","link":"https:\/\/ifamnews.com\/de\/christlicher-demonstrant-verhaftet-weil-er-auf-einer-lgbt-veranstaltung-aus-der-bibel-zitierte","title":{"rendered":"Christlicher Demonstrant verhaftet, weil er auf einer LGBT-Veranstaltung aus der Bibel zitierte"},"content":{"rendered":"\n<p><br>Ein christlicher Demonstrant, Damon Atkins, wurde in Reading, Pennsylvania, in Gewahrsam genommen, weil er Bibelverse als Gegendarstellung zu einem LGBT-&#8222;Pride March and Rally&#8220; rezitiert hatte. Der Vorfall ereignete sich am 3. Juni w\u00e4hrend des allerersten Pride March der Stadt, einer Veranstaltung, zu der auch das Hissen der Flagge am Rathausgeb\u00e4ude und Teilnehmer in \u00fcbertriebener weiblicher Kleidung geh\u00f6rten. Atkins wurde wegen &#8222;kriminellen Fehlverhaltens&#8220; verhaftet, nachdem er begonnen hatte, gegen die Veranstaltung auf der anderen Stra\u00dfenseite zu predigen, w\u00e4hrend er ein Schild mit der Aufschrift &#8222;Gott sagt: Geht und s\u00fcndigt nicht mehr&#8220; trug und ein Hemd mit der Botschaft &#8222;Ihr m\u00fcsst neu geboren werden&#8220;.<\/p>\n\n\n\n<p>Matthew Wear, ein weiterer Einwohner von Reading, der von der Polizei aufgefordert worden war, mit dem Predigen aufzuh\u00f6ren, zeichnete die Verhaftung von Atkins auf, die sich ereignete, nachdem Atkins etwa eine Minute lang gepredigt hatte. Der festnehmende Beamte, Sgt. Bradley T. McClure, forderte Atkins auf, den Pride-Anh\u00e4ngern &#8222;ihren Tag zu lassen&#8220;, woraufhin Atkins sich auf sein Recht berief, sich auf \u00f6ffentlichem Gel\u00e4nde aufzuhalten, und weiterhin seine \u00dcberzeugungen kundtat.<\/p>\n\n\n\n<p>Nach einem kurzen Spaziergang wandte sich McClure wieder Atkins zu, der einen Vers aus 1. Korinther 14:33 zu zitieren begann. Atkins war nur in der Lage, den Anfang des Verses zu sprechen, bevor er von McClure unterbrochen wurde, der erkl\u00e4rte: &#8222;Das war&#8217;s. Daraufhin wurde Atkins in Handschellen gelegt und von McClure und zwei weiteren Beamten festgenommen.<\/p>\n\n\n\n<p>Laut den Dokumenten, die der Lancaster Patriot erhalten hat, wurde Atkins wegen &#8222;ordnungswidrigen Verhaltens und Beteiligung an einer Schl\u00e4gerei&#8220; angeklagt. In der eidesstattlichen Erkl\u00e4rung \u00fcber den hinreichenden Verdacht stellte McClure fest, dass Atkins begonnen hatte, &#8222;die Leute auf der Veranstaltung anzuschreien&#8220;, weshalb er festgenommen wurde. Atkins wurde angewiesen, auf seiner Stra\u00dfenseite zu bleiben und sein Schild zu halten, ohne die Veranstaltung zu st\u00f6ren, aber der Beamte behauptete, dass Atkins trotz der Kenntnisnahme der Anweisungen die Teilnehmer der Veranstaltung weiter angeschrien habe.<\/p>\n\n\n\n<p>In seiner Antwort bestreitet Atkins, den Befehlen des Beamten zugestimmt zu haben, und weist die Anschuldigungen zur\u00fcck, &#8222;abf\u00e4llige Bemerkungen&#8220; gemacht zu haben. Er brachte seine Best\u00fcrzung dar\u00fcber zum Ausdruck, dass der Begriff &#8222;Gott&#8220; heute als abwertend angesehen wird, und bekr\u00e4ftigte sein Bekenntnis zu den Lehren von Jesus. Atkins, der am 16. Juni vor Gericht erscheinen soll, hofft weiterhin, dass die konservative Rechtsgruppe Alliance Defending Freedom ihm rechtlichen Beistand gew\u00e4hrt. Trotz seiner misslichen Lage ist er dankbar f\u00fcr die Unterst\u00fctzung, die er von der \u00d6ffentlichkeit erhalten hat.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Atkins wurde wegen &#8222;kriminellen Fehlverhaltens&#8220; verhaftet, nachdem er begonnen hatte, gegen die Veranstaltung auf der anderen Stra\u00dfenseite zu predigen, w\u00e4hrend er ein Schild mit der Aufschrift &#8222;Gott sagt: Geht und s\u00fcndigt nicht mehr&#8220; trug und ein Hemd mit der Botschaft &#8222;Ihr m\u00fcsst neu geboren werden&#8220;.<\/p>\n","protected":false},"author":593,"featured_media":197812,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"mc4wp_mailchimp_campaign":[],"jnews-multi-image_gallery":[],"jnews_single_post":{"subtitle":"Atkins wurde wegen \"kriminellen Fehlverhaltens\" verhaftet, nachdem er begonnen hatte, gegen die Veranstaltung auf der anderen Stra\u00dfenseite zu predigen, w\u00e4hrend er ein Schild mit der Aufschrift \"Gott sagt: Geht und s\u00fcndigt nicht mehr\" trug und ein Hemd mit der Botschaft \"Ihr m\u00fcsst neu geboren werden\".","format":"standard","video":"","gallery":"","source_name":"","source_url":"","via_name":"","via_url":"","override_template":"0","override":[{"template":"2","single_blog_custom":"","parallax":"1","fullscreen":"1","layout":"right-sidebar-narrow","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"float","share_float_style":"share-normal","show_share_counter":"1","show_view_counter":"1","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","show_post_reading_time":"1","post_reading_time_wpm":"300","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","show_prev_next_post":"0","show_popup_post":"0","number_popup_post":"1","show_author_box":"1","show_post_related":"0","show_inline_post_related":"0"}],"override_image_size":"0","image_override":[{"single_post_thumbnail_size":"crop-715","single_post_gallery_size":"crop-715"}],"trending_post":"0","trending_post_position":"meta","trending_post_label":"Trending","sponsored_post":"0","sponsored_post_label":"Sponsored by","sponsored_post_name":"","sponsored_post_url":"","sponsored_post_logo_enable":"0","sponsored_post_logo":"","sponsored_post_desc":"","disable_ad":"0"},"jnews_primary_category":{"id":"763"},"jnews_social_meta":{"fb_title":"","fb_description":"","fb_image":"","twitter_title":"","twitter_description":"","twitter_image":""},"jnews_override_counter":{"override_view_counter":"0","view_counter_number":"0","override_share_counter":"0","share_counter_number":"0","override_like_counter":"0","like_counter_number":"0","override_dislike_counter":"0","dislike_counter_number":"0"},"footnotes":""},"categories":[816,763,811],"tags":[5234,6941,9204,5237],"class_list":["post-197821","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news-de","category-kultur","category-foreground-de","tag-gender-ideology-de","tag-lgbt-ideologie","tag-lgbt-de-2","tag-transgenderism-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.9 (Yoast SEO v27.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Christlicher Demonstrant verhaftet, weil er auf einer LGBT-Veranstaltung aus der Bibel zitierte - IFN<\/title>\n<meta name=\"description\" content=\"Ein christlicher Demonstrant, Damon Atkins, wurde in Reading, Pennsylvania, in Gewahrsam genommen, weil er Bibelverse als Gegendarstellung zu einem LGBT &quot;Pride March and Rally&quot; rezitiert hatte.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ifamnews.com\/de\/christlicher-demonstrant-verhaftet-weil-er-auf-einer-lgbt-veranstaltung-aus-der-bibel-zitierte\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Christlicher Demonstrant verhaftet, weil er auf einer LGBT-Veranstaltung aus der Bibel zitierte\" \/>\n<meta property=\"og:description\" content=\"Ein christlicher Demonstrant, Damon Atkins, wurde in Reading, Pennsylvania, in Gewahrsam genommen, weil er Bibelverse als Gegendarstellung zu einem LGBT &quot;Pride March and Rally&quot; rezitiert hatte.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ifamnews.com\/de\/christlicher-demonstrant-verhaftet-weil-er-auf-einer-lgbt-veranstaltung-aus-der-bibel-zitierte\" \/>\n<meta property=\"og:site_name\" content=\"IFN\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/iFamNews\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/iFamNews\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-13T06:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ifamnews.com\/wp-content\/uploads\/2023\/06\/Untitled-design-78.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"IFN English\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/iFamNewsEN\" \/>\n<meta name=\"twitter:site\" content=\"@iFamNewsEN\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"iFamNews Redaktion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Christlicher Demonstrant verhaftet, weil er auf einer LGBT-Veranstaltung aus der Bibel zitierte - IFN","description":"Ein christlicher Demonstrant, Damon Atkins, wurde in Reading, Pennsylvania, in Gewahrsam genommen, weil er Bibelverse als Gegendarstellung zu einem LGBT \"Pride March and Rally\" rezitiert hatte.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ifamnews.com\/de\/christlicher-demonstrant-verhaftet-weil-er-auf-einer-lgbt-veranstaltung-aus-der-bibel-zitierte","og_locale":"de_DE","og_type":"article","og_title":"Christlicher Demonstrant verhaftet, weil er auf einer LGBT-Veranstaltung aus der Bibel zitierte","og_description":"Ein christlicher Demonstrant, Damon Atkins, wurde in Reading, Pennsylvania, in Gewahrsam genommen, weil er Bibelverse als Gegendarstellung zu einem LGBT \"Pride March and Rally\" rezitiert hatte.","og_url":"https:\/\/ifamnews.com\/de\/christlicher-demonstrant-verhaftet-weil-er-auf-einer-lgbt-veranstaltung-aus-der-bibel-zitierte","og_site_name":"IFN","article_publisher":"https:\/\/www.facebook.com\/iFamNews","article_author":"https:\/\/www.facebook.com\/iFamNews\/","article_published_time":"2023-06-13T06:00:00+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/ifamnews.com\/wp-content\/uploads\/2023\/06\/Untitled-design-78.png","type":"image\/png"}],"author":"IFN English","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/iFamNewsEN","twitter_site":"@iFamNewsEN","twitter_misc":{"Verfasst von":"iFamNews Redaktion","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/ifamnews.com\/de\/christlicher-demonstrant-verhaftet-weil-er-auf-einer-lgbt-veranstaltung-aus-der-bibel-zitierte#article","isPartOf":{"@id":"https:\/\/ifamnews.com\/de\/christlicher-demonstrant-verhaftet-weil-er-auf-einer-lgbt-veranstaltung-aus-der-bibel-zitierte"},"author":{"name":"IFN English","@id":"https:\/\/ifamnews.com\/en\/#\/schema\/person\/633bdb7ac2496c9b9304ce62d071cdfa"},"headline":"Christlicher Demonstrant verhaftet, weil er auf einer LGBT-Veranstaltung aus der Bibel zitierte","datePublished":"2023-06-13T06:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/ifamnews.com\/de\/christlicher-demonstrant-verhaftet-weil-er-auf-einer-lgbt-veranstaltung-aus-der-bibel-zitierte"},"wordCount":426,"commentCount":0,"publisher":{"@id":"https:\/\/ifamnews.com\/en\/#organization"},"image":{"@id":"https:\/\/ifamnews.com\/de\/christlicher-demonstrant-verhaftet-weil-er-auf-einer-lgbt-veranstaltung-aus-der-bibel-zitierte#primaryimage"},"thumbnailUrl":"https:\/\/ifamnews.com\/wp-content\/uploads\/2023\/06\/Untitled-design-78.png","keywords":["gender ideology","LGBT-Ideologie","LGBT+","Transgenderism"],"articleSection":["Breaking News","Kultur","Vordergrund"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ifamnews.com\/de\/christlicher-demonstrant-verhaftet-weil-er-auf-einer-lgbt-veranstaltung-aus-der-bibel-zitierte#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ifamnews.com\/de\/christlicher-demonstrant-verhaftet-weil-er-auf-einer-lgbt-veranstaltung-aus-der-bibel-zitierte","url":"https:\/\/ifamnews.com\/de\/christlicher-demonstrant-verhaftet-weil-er-auf-einer-lgbt-veranstaltung-aus-der-bibel-zitierte","name":"Christlicher Demonstrant verhaftet, weil er auf einer LGBT-Veranstaltung aus der Bibel zitierte - IFN","isPartOf":{"@id":"https:\/\/ifamnews.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ifamnews.com\/de\/christlicher-demonstrant-verhaftet-weil-er-auf-einer-lgbt-veranstaltung-aus-der-bibel-zitierte#primaryimage"},"image":{"@id":"https:\/\/ifamnews.com\/de\/christlicher-demonstrant-verhaftet-weil-er-auf-einer-lgbt-veranstaltung-aus-der-bibel-zitierte#primaryimage"},"thumbnailUrl":"https:\/\/ifamnews.com\/wp-content\/uploads\/2023\/06\/Untitled-design-78.png","datePublished":"2023-06-13T06:00:00+00:00","description":"Ein christlicher Demonstrant, Damon Atkins, wurde in Reading, Pennsylvania, in Gewahrsam genommen, weil er Bibelverse als Gegendarstellung zu einem LGBT \"Pride March and Rally\" rezitiert hatte.","breadcrumb":{"@id":"https:\/\/ifamnews.com\/de\/christlicher-demonstrant-verhaftet-weil-er-auf-einer-lgbt-veranstaltung-aus-der-bibel-zitierte#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ifamnews.com\/de\/christlicher-demonstrant-verhaftet-weil-er-auf-einer-lgbt-veranstaltung-aus-der-bibel-zitierte"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ifamnews.com\/de\/christlicher-demonstrant-verhaftet-weil-er-auf-einer-lgbt-veranstaltung-aus-der-bibel-zitierte#primaryimage","url":"https:\/\/ifamnews.com\/wp-content\/uploads\/2023\/06\/Untitled-design-78.png","contentUrl":"https:\/\/ifamnews.com\/wp-content\/uploads\/2023\/06\/Untitled-design-78.png","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/ifamnews.com\/de\/christlicher-demonstrant-verhaftet-weil-er-auf-einer-lgbt-veranstaltung-aus-der-bibel-zitierte#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ifamnews.com\/de"},{"@type":"ListItem","position":2,"name":"\u041a\u0443\u043b\u0442\u0443\u0440\u0430","item":"https:\/\/ifamnews.com\/sr\/kategorija\/kultura-sr"},{"@type":"ListItem","position":3,"name":"Christlicher Demonstrant verhaftet, weil er auf einer LGBT-Veranstaltung aus der Bibel zitierte"}]},{"@type":"WebSite","@id":"https:\/\/ifamnews.com\/en\/#website","url":"https:\/\/ifamnews.com\/en\/","name":"IFN","description":"International Family News Network","publisher":{"@id":"https:\/\/ifamnews.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ifamnews.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/ifamnews.com\/en\/#organization","name":"iFamNews","url":"https:\/\/ifamnews.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ifamnews.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/ifamnews.com\/wp-content\/uploads\/2020\/01\/Share-logo.png","contentUrl":"https:\/\/ifamnews.com\/wp-content\/uploads\/2020\/01\/Share-logo.png","width":200,"height":200,"caption":"iFamNews"},"image":{"@id":"https:\/\/ifamnews.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/iFamNews","https:\/\/x.com\/iFamNewsEN"]},{"@type":"Person","@id":"https:\/\/ifamnews.com\/en\/#\/schema\/person\/633bdb7ac2496c9b9304ce62d071cdfa","name":"IFN English","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/6f16ce95b558ae6f6eb9ae2f68122482a2c61696af2a8fc343c2e10f981a959d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6f16ce95b558ae6f6eb9ae2f68122482a2c61696af2a8fc343c2e10f981a959d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6f16ce95b558ae6f6eb9ae2f68122482a2c61696af2a8fc343c2e10f981a959d?s=96&d=mm&r=g","caption":"IFN English"},"description":"Articles published by the English iFamNews editorial team.","sameAs":["https:\/\/ifamnews.com\/en","https:\/\/www.facebook.com\/iFamNews\/","https:\/\/x.com\/https:\/\/twitter.com\/iFamNewsEN","https:\/\/www.youtube.com\/channel\/UCMVyIt4z9BANW3d09kwfUpw"],"url":"https:\/\/ifamnews.com\/de\/author\/ifamnews-staff"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ifamnews.com\/de\/wp-json\/wp\/v2\/posts\/197821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ifamnews.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ifamnews.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ifamnews.com\/de\/wp-json\/wp\/v2\/users\/593"}],"replies":[{"embeddable":true,"href":"https:\/\/ifamnews.com\/de\/wp-json\/wp\/v2\/comments?post=197821"}],"version-history":[{"count":4,"href":"https:\/\/ifamnews.com\/de\/wp-json\/wp\/v2\/posts\/197821\/revisions"}],"predecessor-version":[{"id":197959,"href":"https:\/\/ifamnews.com\/de\/wp-json\/wp\/v2\/posts\/197821\/revisions\/197959"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ifamnews.com\/de\/wp-json\/wp\/v2\/media\/197812"}],"wp:attachment":[{"href":"https:\/\/ifamnews.com\/de\/wp-json\/wp\/v2\/media?parent=197821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ifamnews.com\/de\/wp-json\/wp\/v2\/categories?post=197821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ifamnews.com\/de\/wp-json\/wp\/v2\/tags?post=197821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}